{"id":1703,"date":"2023-05-08T21:27:37","date_gmt":"2023-05-08T18:27:37","guid":{"rendered":"https:\/\/stella.villas\/?page_id=1703"},"modified":"2024-10-08T10:48:55","modified_gmt":"2024-10-08T07:48:55","slug":"experiences","status":"publish","type":"page","link":"https:\/\/stella.villas\/de\/experiences\/","title":{"rendered":"Erfahrungen"},"content":{"rendered":"<div id=\"fws_6a97bae60d2d3\"  data-column-margin=\"default\" data-midnight=\"light\" data-top-percent=\"6%\" data-bottom-percent=\"6%\"  class=\"wpb_row vc_row-fluid vc_row full-width-content vc_row-o-equal-height vc_row-flex vc_row-o-content-top  nectar-overflow-hidden\"  style=\"padding-top: calc(100vw * 0.06); padding-bottom: calc(100vw * 0.06); \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"false\"><div class=\"inner-wrap row-bg-layer\" ><div class=\"row-bg viewport-desktop\"  style=\"\"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 light left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col no-extra-padding el_spacing_0px inherit_tablet inherit_phone\"  data-padding-pos=\"top-bottom\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t<div id=\"fws_6a97bae60dd46\" data-midnight=\"\" data-column-margin=\"none\" class=\"wpb_row vc_row-fluid vc_row inner_row  no-pointer-events right_padding_8pct left_padding_8pct translate_y_26pct\"  style=\" z-index: 200;\"><div class=\"row-bg-wrap\"> <div class=\"row-bg\" ><\/div> <\/div><div class=\"row_col_wrap_12_inner col span_12  left\">\n\t<div style=\"margin-bottom: 4%; \" class=\"vc_col-sm-12 wpb_column column_container vc_column_container col child_column centered-text no-extra-padding el_spacing_0px inherit_tablet inherit_phone\"   data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" data-scroll-animation=\"true\" data-scroll-animation-movement=\"default\" data-scroll-animation-mobile=\"true\" data-scroll-animation-intensity=\"1\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h1 style=\"font-size: 5vw;color: #70675d;line-height: 1.5;text-align: center\" class=\"vc_custom_heading vc_do_custom_heading wpb_animate_when_almost_visible wpb_fadeInUp fadeInUp\" >Erleben Sie es in vollen Z\u00fcgen<\/h1><h1 style=\"font-size: 12vw;color: #70675d;line-height: 0.8;text-align: center\" class=\"vc_custom_heading vc_do_custom_heading wpb_animate_when_almost_visible wpb_fadeInUp fadeInUp\" >ERLEBNISSE<\/h1>\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n<\/div><\/div><div id=\"nomobile\" data-midnight=\"\" data-column-margin=\"default\" class=\"wpb_row vc_row-fluid vc_row inner_row nomobile row_position_absolute top_position_desktop_10px left_position_desktop_0px row_position_tablet_relative\"  style=\"\"><div class=\"row-bg-wrap\"> <div class=\"row-bg\" ><\/div> <\/div><div class=\"row_col_wrap_12_inner col span_12  left\">\n\t<div  class=\"vc_col-sm-6 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone\"   data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"img-with-aniamtion-wrap\" data-max-width=\"100%\" data-max-width-mobile=\"default\" data-shadow=\"none\" data-animation=\"grow-in\" >\n      <div class=\"inner\">\n        <div class=\"hover-wrap\"> \n          <div class=\"hover-wrap-inner\">\n            <img loading=\"lazy\" decoding=\"async\" class=\"img-with-animation skip-lazy\" data-delay=\"0\" height=\"1042\" width=\"1135\" data-animation=\"grow-in\" src=\"https:\/\/stella.villas\/wp-content\/uploads\/2023\/04\/pattern1-09.png\" alt=\"Villas Rethymno - Rethymno Accommodation - Modern Crete Vacation Rental - Hillside Villas in Myrthios\" srcset=\"https:\/\/stella.villas\/wp-content\/uploads\/2023\/04\/pattern1-09.png 1135w, https:\/\/stella.villas\/wp-content\/uploads\/2023\/04\/pattern1-09-300x275.png 300w, https:\/\/stella.villas\/wp-content\/uploads\/2023\/04\/pattern1-09-1024x940.png 1024w, https:\/\/stella.villas\/wp-content\/uploads\/2023\/04\/pattern1-09-768x705.png 768w\" sizes=\"auto, (max-width: 1135px) 100vw, 1135px\" \/>\n          <\/div>\n        <\/div>\n      <\/div>\n    <\/div>\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-6 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone\"   data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t<div id=\"fws_6a97bae610075\"  data-column-margin=\"default\" data-midnight=\"dark\"  class=\"wpb_row vc_row-fluid vc_row\"  style=\"padding-top: 0px; padding-bottom: 0px; \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"false\"><div class=\"inner-wrap row-bg-layer\" ><div class=\"row-bg viewport-desktop\"  style=\"\"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div style=\"\" class=\"vc_col-sm-12 wpb_column column_container vc_column_container col padding-5-percent inherit_tablet inherit_phone mask_shape_circle-rect mask_size_contain\" data-using-bg=\"true\" data-padding-pos=\"all\" data-has-bg-color=\"true\" data-bg-color=\"#ffffff\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" ><div class=\"column-bg-overlay-wrap column-bg-layer\" data-bg-animation=\"none\"><div class=\"column-bg-overlay\" style=\"opacity: 1; background-color: #ffffff;\"><\/div><\/div>\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\n<div class=\"wpb_text_column wpb_content_element  wpb_animate_when_almost_visible wpb_fadeInUp fadeInUp\" >\n\t<div class=\"wpb_wrapper\">\n\t\t<p>Es gibt keinen Mangel an Aktivit\u00e4ten, die Sie w\u00e4hrend Ihres Aufenthalts in der Umgebung genie\u00dfen k\u00f6nnen. Von spannenden Natur-Abenteuern bis hin zu kulturellen Erlebnissen bieten wir eine breite Palette an Aktivit\u00e4ten, die jedem Interesse und jeder Vorliebe gerecht werden. Machen Sie eine Fluss-Trekking-Tour, erkunden Sie die Landschaft auf einer Radtour oder fordern Sie sich mit einer Klettertour heraus. Nehmen Sie an einer Bootstour teil, um die verborgenen Sch\u00e4tze der S\u00fcdk\u00fcste zu entdecken, oder tauchen Sie bei unseren Besichtigungs- und Kulturtouren in die lokale Kultur ein. Was auch immer Ihre Vorstellung vom perfekten Urlaub ist, wir haben die Aktivit\u00e4ten, um ihn Wirklichkeit werden zu lassen.<\/p>\n\t<\/div>\n<\/div>\n\n\n\n\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t<div id=\"experiences\"  data-column-margin=\"20px\" data-midnight=\"light\" data-top-percent=\"6%\" data-bottom-percent=\"6%\"  class=\"wpb_row vc_row-fluid vc_row full-width-section\"  style=\"padding-top: calc(100vw * 0.06); padding-bottom: calc(100vw * 0.06); \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"false\"><div class=\"inner-wrap row-bg-layer\" ><div class=\"row-bg viewport-desktop\"  style=\"\"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 light left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t<div id=\"fws_6a97bae611241\" data-midnight=\"\" data-column-margin=\"20px\" class=\"wpb_row vc_row-fluid vc_row inner_row\"  style=\"\"><div class=\"row-bg-wrap\"> <div class=\"row-bg\" ><\/div> <\/div><div class=\"row_col_wrap_12_inner col span_12  left\">\n\t<div  class=\"vc_col-sm-6 wpb_column column_container vc_column_container col child_column has-animation no-extra-padding inherit_tablet inherit_phone\"   data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"fade-in-from-bottom\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"nectar-fancy-box using-img  has-animation min_height_tablet_550px\" style=\"min-height: 70vh\" data-style=\"hover_desc\" data-border-radius=\"default\" data-animation=\"fade-in-from-bottom\" data-bg-animation=\"long_zoom\" data-border=\"\" data-delay=\"0\" data-alignment=\"left\" data-color=\"accent-color\" ><div class=\"box-bg\"  data-nectar-img-src=\"https:\/\/stella.villas\/wp-content\/uploads\/2023\/04\/scuba-diving.jpg\"><\/div><div class=\"inner\"><div class=\"heading-wrap\"><span class=\"im-icon-wrap\" data-color=\"accent-color\"><span><svg role=\"presentation\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"30\" height=\"30\" viewbox=\"0 0 32 32\">\n        <path d=\"M16.061 4.501c-1.675 0-2.985-0.917-2.985-2.084 0-1.169 1.311-2.084 2.985-2.084s2.987 0.916 2.987 2.084c0 1.168-1.312 2.084-2.987 2.084zM16.061 1.667c-0.993 0-1.652 0.452-1.652 0.751 0 0.303 0.659 0.751 1.652 0.751s1.653-0.452 1.653-0.751c0-0.3-0.66-0.751-1.653-0.751zM27.012 18.333c-0.368 0-0.667-0.3-0.667-0.667 0-3.685-3.603-12.696-10.284-12.696-6.68 0-10.284 9.011-10.284 12.696 0 0.367-0.299 0.667-0.667 0.667s-0.667-0.3-0.667-0.667c0-4.196 3.953-14.029 11.617-14.029s11.617 9.833 11.617 14.029c0 0.367-0.299 0.667-0.667 0.667zM26 31.667h-6.773c-0.323 0-0.599-0.232-0.656-0.552-0.301-1.695-1.541-3.669-2.695-3.669-1.171 0-2.389 1.937-2.697 3.672-0.056 0.317-0.333 0.549-0.655 0.549h-6.524c-3.307 0-6-2.693-6-6v-3.093c0-2.063 1.3-3.937 3.232-4.664 2.945-1.107 7.599-1.74 12.768-1.74s9.823 0.633 12.768 1.74c1.932 0.727 3.232 2.601 3.232 4.664v3.093c0 3.307-2.693 6-6 6zM19.76 30.333h6.24c2.573 0 4.667-2.093 4.667-4.667v-3.093c0-1.511-0.952-2.885-2.367-3.417-2.755-1.033-7.359-1.651-12.3-1.651s-9.539 0.617-12.3 1.651c-1.417 0.532-2.367 1.907-2.367 3.417v3.093c0 2.573 2.093 4.667 4.667 4.667h5.988c0.5-1.872 1.925-4.221 3.887-4.221 1.96 0 3.385 2.349 3.885 4.221zM26 29h-4.82c-0.263 0-0.504-0.156-0.611-0.399-0.811-1.849-2.472-3.823-4.695-3.823s-3.881 1.973-4.695 3.823c-0.107 0.243-0.347 0.399-0.611 0.399h-4.569c-1.839 0-3.333-1.495-3.333-3.333v-3.093c0-0.961 0.604-1.831 1.504-2.169 2.615-0.979 7.035-1.571 11.829-1.571 4.792 0 9.215 0.585 11.831 1.571 0.899 0.339 1.503 1.211 1.503 2.169v3.093c0 1.839-1.495 3.333-3.333 3.333zM21.605 27.667h4.395c1.103 0 2-0.899 2-2v-3.093c0-0.407-0.255-0.779-0.639-0.919-2.473-0.924-6.721-1.479-11.361-1.479s-8.888 0.555-11.361 1.479c-0.384 0.143-0.639 0.52-0.639 0.919v3.093c0 1.101 0.897 2 2 2h4.143c1.296-2.651 3.415-4.221 5.732-4.221s4.435 1.571 5.731 4.221zM6.109 23.604c-0.277 0-0.536-0.175-0.631-0.451-0.12-0.349 0.067-0.729 0.415-0.847 0.407-0.139 0.855-0.268 1.34-0.385 0.356-0.088 0.717 0.133 0.805 0.489s-0.133 0.716-0.489 0.805c-0.444 0.109-0.855 0.227-1.223 0.355-0.075 0.020-0.144 0.033-0.217 0.033zM10.013 22.763c-0.328 0-0.616-0.251-0.659-0.584-0.047-0.361 0.208-0.697 0.573-0.751 0.435-0.055 0.885-0.107 1.351-0.151 0.361-0.019 0.695 0.235 0.729 0.599 0.035 0.367-0.233 0.695-0.595 0.732-0.451 0.039-0.883 0.088-1.305 0.143-0.035 0.009-0.065 0.012-0.095 0.012z\"><\/path>\n        <\/svg><\/span><\/span>\n<h4>Tauchen und Schnorcheln in Plakias<\/h4>\n<\/div><div class=\"hover-content\">Erkunden Sie die Unterwassersch\u00f6nheiten von Plakias mit unseren Tauch- und Schnorcheltouren. Egal, ob Sie ein erfahrener Taucher oder ein Anf\u00e4nger sind, unsere erfahrenen Tauchlehrer f\u00fchren Sie durch das kristallklare Wasser, um atemberaubende Korallenriffe, farbenfrohe Fische und andere faszinierende Meereslebewesen zu entdecken. Mit einfachem Zugang zu einigen der besten Tauchpl\u00e4tze in der Umgebung, werden Sie sicher ein unvergessliches Unterwasser-Abenteuer erleben.<\/div><\/div>   <\/div>\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-6 wpb_column column_container vc_column_container col child_column has-animation no-extra-padding inherit_tablet inherit_phone\"   data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"fade-in-from-bottom\" data-delay=\"50\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"nectar-fancy-box using-img  has-animation min_height_tablet_550px\" style=\"min-height: 70vh\" data-style=\"hover_desc\" data-border-radius=\"default\" data-animation=\"fade-in-from-bottom\" data-bg-animation=\"long_zoom\" data-border=\"\" data-delay=\"10\" data-alignment=\"left\" data-color=\"accent-color\" ><div class=\"box-bg\"  data-nectar-img-src=\"https:\/\/stella.villas\/wp-content\/uploads\/2023\/07\/trekking-excursions-and-walks.jpg\"><\/div><div class=\"inner\"><div class=\"heading-wrap\"><span class=\"im-icon-wrap\" data-color=\"accent-color\"><span><svg role=\"presentation\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"30\" height=\"30\" viewbox=\"0 0 32 32\">\n        <path d=\"M14.253 30.18c-0.015 0-0.029 0-0.047-0.003-3.431-0.237-6.265-1.631-8.425-4.143-3.521-4.1-5.069-11.008-4.363-19.451 0.029-0.361 0.321-0.66 0.703-0.609 4.747 0.277 9.948 3.045 13.576 7.224 3.303 3.801 4.924 8.252 4.572 12.539-0.031 0.364-0.339 0.628-0.72 0.609-0.367-0.031-0.64-0.355-0.611-0.719 0.323-3.924-1.187-8.028-4.249-11.556-3.232-3.724-7.772-6.251-11.995-6.712-0.532 7.676 0.947 14.14 4.095 17.807 1.917 2.232 4.444 3.472 7.505 3.68 0.367 0.027 0.644 0.344 0.62 0.711-0.019 0.352-0.312 0.623-0.661 0.623zM17.748 31.361c-0.305 0-0.58-0.211-0.649-0.521-1.608-7.159-9.288-16.467-12.544-19.611-0.265-0.253-0.273-0.675-0.019-0.941 0.256-0.264 0.68-0.271 0.943-0.019 3.347 3.236 11.245 12.827 12.919 20.277 0.081 0.361-0.145 0.713-0.504 0.8-0.048 0.011-0.097 0.015-0.145 0.015zM19.671 24.289c-0.309 0-0.585-0.216-0.652-0.531-0.076-0.36 0.156-0.713 0.516-0.789 10.043-2.101 10.111-15.788 9.765-20.943-5.8 0.629-11.848 5.075-14.577 10.795-0.159 0.333-0.559 0.472-0.889 0.315-0.332-0.159-0.473-0.556-0.315-0.888 3.028-6.348 9.907-11.229 16.356-11.607 0.355-0.035 0.675 0.251 0.703 0.609 1.072 12.781-2.955 21.388-10.771 23.025-0.047 0.008-0.091 0.013-0.136 0.013zM17.747 18.057c-0.115 0-0.231-0.028-0.336-0.091-0.317-0.188-0.424-0.593-0.237-0.915 3.067-5.233 7.295-10.143 9.389-12.169 0.267-0.252 0.688-0.249 0.943 0.019 0.255 0.261 0.249 0.688-0.016 0.943-2.041 1.972-6.167 6.765-9.167 11.887-0.125 0.207-0.348 0.327-0.576 0.327z\"><\/path>\n        <\/svg><\/span><\/span>\n<h4>Wandern, Ausfl\u00fcge und Spazierg\u00e4nge<\/h4>\n<\/div><div class=\"hover-content\">Entdecken Sie die nat\u00fcrliche Sch\u00f6nheit der Umgebung auf unseren gef\u00fchrten Wanderungen, Ausfl\u00fcgen und Spazierg\u00e4ngen. Mit atemberaubenden Berg- und K\u00fcstenlandschaften nehmen unsere erfahrenen F\u00fchrer Sie mit auf eine Reise, um versteckte Pfade und atemberaubende Ausblicke zu erkunden. Schn\u00fcren Sie also Ihre Stiefel, greifen Sie zu Ihrer Kamera und machen Sie sich bereit, die Sch\u00f6nheit der Natur zu erleben.<\/div><\/div>   <\/div>\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n<\/div><\/div><div id=\"fws_6a97bae616d3b\" data-midnight=\"\" data-column-margin=\"20px\" class=\"wpb_row vc_row-fluid vc_row inner_row\"  style=\"\"><div class=\"row-bg-wrap\"> <div class=\"row-bg\" ><\/div> <\/div><div class=\"row_col_wrap_12_inner col span_12  left\">\n\t<div  class=\"vc_col-sm-6 wpb_column column_container vc_column_container col child_column has-animation no-extra-padding inherit_tablet inherit_phone\"   data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"fade-in-from-bottom\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"nectar-fancy-box using-img  has-animation min_height_tablet_550px\" style=\"min-height: 70vh\" data-style=\"hover_desc\" data-border-radius=\"default\" data-animation=\"fade-in-from-bottom\" data-bg-animation=\"long_zoom\" data-border=\"\" data-delay=\"0\" data-alignment=\"left\" data-color=\"accent-color\" ><div class=\"box-bg\"  data-nectar-img-src=\"https:\/\/stella.villas\/wp-content\/uploads\/2023\/04\/jeep-safari.jpg\"><\/div><div class=\"inner\"><div class=\"heading-wrap\"><span class=\"im-icon-wrap\" data-color=\"accent-color\"><span><svg role=\"presentation\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"30\" height=\"30\" viewbox=\"0 0 32 32\">\n        <path d=\"M30 22.912h-28c-0.367 0-0.667-0.3-0.667-0.667v-4c0-1.609 1.145-2.956 2.667-3.267v-10.359c0-2.416 1.964-4.375 4.375-4.375h15.251c2.413 0 4.375 1.964 4.375 4.375v10.359c1.521 0.308 2.667 1.657 2.667 3.267v4c0 0.367-0.3 0.667-0.667 0.667zM2.667 21.579h26.667v-3.333c0-1.101-0.897-2-2-2-0.367 0-0.667-0.3-0.667-0.667v-10.959c0-1.677-1.364-3.041-3.041-3.041h-15.251c-1.677 0-3.041 1.365-3.041 3.041v10.959c0 0.367-0.3 0.667-0.667 0.667-1.103 0-2 0.897-2 2v3.333zM4.667 13.579h-2.667c-0.367 0-0.667-0.3-0.667-0.667v-6.667c0-0.367 0.3-0.667 0.667-0.667h2.667c0.367 0 0.667 0.3 0.667 0.667v6.667c0 0.367-0.3 0.667-0.667 0.667zM2.667 12.245h1.333v-5.333h-1.333v5.333zM30 13.579h-2.667c-0.367 0-0.667-0.3-0.667-0.667v-6.667c0-0.367 0.3-0.667 0.667-0.667h2.667c0.367 0 0.667 0.3 0.667 0.667v6.667c0 0.367-0.3 0.667-0.667 0.667zM28 12.245h1.333v-5.333h-1.333v5.333zM7.279 20.691c-1.103 0-2-0.896-2-2 0-1.101 0.897-2 2-2s2 0.899 2 2c0 1.104-0.897 2-2 2zM7.279 18.024c-0.367 0-0.667 0.3-0.667 0.667s0.3 0.667 0.667 0.667 0.667-0.3 0.667-0.667-0.3-0.667-0.667-0.667zM24.612 20.691c-1.103 0-2-0.896-2-2 0-1.101 0.897-2 2-2s2 0.899 2 2c0 1.104-0.897 2-2 2zM24.612 18.024c-0.367 0-0.667 0.3-0.667 0.667s0.3 0.667 0.667 0.667 0.667-0.3 0.667-0.667-0.3-0.667-0.667-0.667zM20 17.579h-8c-0.367 0-0.667-0.3-0.667-0.667s0.3-0.667 0.667-0.667h8c0.367 0 0.667 0.3 0.667 0.667s-0.3 0.667-0.667 0.667zM20 20.245h-8c-0.367 0-0.667-0.3-0.667-0.667s0.3-0.667 0.667-0.667h8c0.367 0 0.667 0.3 0.667 0.667s-0.3 0.667-0.667 0.667zM27.333 26.912h-22.667c-0.223 0-0.431-0.112-0.555-0.297l-2.667-4c-0.139-0.203-0.148-0.469-0.031-0.688 0.113-0.216 0.34-0.353 0.585-0.353h28c0.248 0 0.472 0.139 0.585 0.355 0.117 0.219 0.104 0.479-0.031 0.688l-2.667 4c-0.124 0.184-0.332 0.296-0.555 0.296zM5.024 25.579h21.953l1.779-2.667h-25.508l1.776 2.667zM9.539 31.755c-0.139 0-0.276-0.003-0.417-0.005l-0.679-0.005c-1.044 0.011-1.976 0.005-2.591-0.604-0.345-0.347-0.52-0.833-0.52-1.451v-2.779c0-0.367 0.299-0.667 0.667-0.667s0.667 0.3 0.667 0.667v2.779c0 0.172 0.023 0.399 0.129 0.505 0.221 0.221 0.935 0.219 1.644 0.216l0.701 0.005c0.577 0.013 1.241 0.019 1.417-0.156 0.071-0.068 0.105-0.229 0.105-0.459v-2.891c0-0.367 0.301-0.667 0.667-0.667s0.667 0.3 0.667 0.667v2.891c0 0.604-0.169 1.079-0.503 1.407-0.484 0.483-1.188 0.547-1.955 0.547zM24.205 31.755c-0.139 0-0.276-0.003-0.417-0.005l-0.679-0.005c-1.040 0.011-1.976 0.005-2.591-0.604-0.345-0.347-0.52-0.833-0.52-1.451v-2.779c0-0.367 0.299-0.667 0.667-0.667s0.667 0.3 0.667 0.667v2.779c0 0.172 0.023 0.399 0.129 0.505 0.221 0.221 0.931 0.219 1.644 0.216l0.701 0.005c0.581 0.013 1.241 0.019 1.417-0.156 0.071-0.068 0.105-0.229 0.105-0.459v-2.891c0-0.367 0.301-0.667 0.667-0.667s0.667 0.3 0.667 0.667v2.891c0 0.604-0.169 1.079-0.503 1.407-0.484 0.483-1.188 0.547-1.955 0.547zM16 13.945c-5.305 0-10.612-0.367-11.705-1.107-0.305-0.203-0.385-0.619-0.181-0.924 0.208-0.307 0.623-0.383 0.925-0.183 1.743 1.177 20.18 1.177 21.921 0 0.304-0.201 0.717-0.128 0.923 0.183 0.204 0.305 0.125 0.721-0.184 0.924-1.087 0.74-6.393 1.107-11.699 1.107zM6.708 4.871c-0.172 0-0.341-0.065-0.472-0.195-0.259-0.259-0.259-0.684 0-0.943l1.251-1.251c0.26-0.257 0.683-0.257 0.943 0 0.26 0.26 0.26 0.685 0 0.943l-1.251 1.251c-0.129 0.129-0.3 0.195-0.471 0.195zM6.708 7.62c-0.172 0-0.341-0.065-0.472-0.195-0.259-0.26-0.259-0.683 0-0.943l4-4c0.26-0.26 0.684-0.26 0.943 0 0.26 0.26 0.26 0.683 0 0.943l-4 4c-0.129 0.131-0.3 0.195-0.471 0.195z\"><\/path>\n        <\/svg><\/span><\/span>\n<h4>Jeep-Safari an der S\u00fcdk\u00fcste<\/h4>\n<\/div><div class=\"hover-content\">Erleben Sie die raue Sch\u00f6nheit der S\u00fcdk\u00fcste mit unseren spannenden Jeep-Safari-Touren. Unsere erfahrenen Fahrer nehmen Sie mit auf ein Offroad-Abenteuer auf Panoramastrecken mit Pausen in malerischen D\u00f6rfern, historischen St\u00e4tten und atemberaubenden Aussichtspunkten. Bestaunen Sie den Panoramablick auf die K\u00fcste und werden Sie Zeuge der unber\u00fchrten Sch\u00f6nheit des zerkl\u00fcfteten Gel\u00e4ndes. Ob Naturliebhaber oder Abenteurer, unsere Jeep-Safari-Touren bieten garantiert ein unvergessliches Erlebnis.<\/div><\/div>   <\/div>\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-6 wpb_column column_container vc_column_container col child_column has-animation no-extra-padding inherit_tablet inherit_phone\"   data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"fade-in-from-bottom\" data-delay=\"50\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"nectar-fancy-box using-img  has-animation min_height_tablet_550px\" style=\"min-height: 70vh\" data-style=\"hover_desc\" data-border-radius=\"default\" data-animation=\"fade-in-from-bottom\" data-bg-animation=\"long_zoom\" data-border=\"\" data-delay=\"0\" data-alignment=\"left\" data-color=\"accent-color\" ><div class=\"box-bg\"  data-nectar-img-src=\"https:\/\/stella.villas\/wp-content\/uploads\/2023\/04\/boat-tour.jpg\"><\/div><div class=\"inner\"><div class=\"heading-wrap\"><span class=\"im-icon-wrap\" data-color=\"accent-color\"><span><svg role=\"presentation\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"50\" height=\"50\" viewbox=\"0 0 32 32\">\n        <path d=\"M30.667 27.333h-6.723c-0.103 0-0.201-0.024-0.296-0.069-3.5-1.725-5.352-5.423-5.083-10.144 0.223-3.899 2.064-8.412 5.259-10.937-10.369 1.331-18.132 9.853-18.132 20.484 0 0.367-0.299 0.667-0.667 0.667h-3.692c-0.368 0-0.667-0.3-0.667-0.667s0.299-0.667 0.667-0.667h3.037c0.345-12.019 10.020-21.333 22.309-21.333 0.324 0 0.601 0.233 0.657 0.552 0.056 0.32-0.127 0.633-0.431 0.743-3.765 1.352-6.711 6.076-7.007 11.235-0.235 4.099 1.296 7.301 4.204 8.805h6.563c0.367 0 0.667 0.299 0.667 0.667s-0.3 0.665-0.667 0.665zM8.216 23.924c-0.048 0-0.097-0.005-0.147-0.019-0.36-0.084-0.585-0.437-0.504-0.8 0.971-4.325 3.213-8.199 6.484-11.213 0.272-0.249 0.692-0.229 0.943 0.037 0.249 0.271 0.232 0.695-0.039 0.943-3.071 2.825-5.175 6.465-6.087 10.525-0.071 0.317-0.347 0.527-0.651 0.527z\"><\/path>\n        <\/svg><\/span><\/span>\n<h4>Bootstouren an der S\u00fcdk\u00fcste<\/h4>\n<\/div><div class=\"hover-content\">Entdecken Sie die verborgenen Sch\u00e4tze der S\u00fcdk\u00fcste mit unseren Bootstouren. Segeln Sie auf eine malerische Reise durch kristallklares Wasser mit Stopps an einsamen Str\u00e4nden, versteckten Buchten und charmanten Fischerd\u00f6rfern. Unsere sachkundigen Reiseleiter erz\u00e4hlen Ihnen faszinierende Geschichten \u00fcber die Geschichte und Kultur der Region, w\u00e4hrend Sie sich entspannen und die Sonne genie\u00dfen. Egal, ob Sie eine romantische Bootsfahrt bei Sonnenuntergang oder ein Familienabenteuer suchen, unsere Bootstouren bieten f\u00fcr jeden etwas.<\/div><\/div>   <\/div>\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n<\/div><\/div><div id=\"fws_6a97bae6183ec\" data-midnight=\"\" data-column-margin=\"20px\" class=\"wpb_row vc_row-fluid vc_row inner_row\"  style=\"\"><div class=\"row-bg-wrap\"> <div class=\"row-bg\" ><\/div> <\/div><div class=\"row_col_wrap_12_inner col span_12  left\">\n\t<div  class=\"vc_col-sm-6 wpb_column column_container vc_column_container col child_column has-animation no-extra-padding inherit_tablet inherit_phone\"   data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"fade-in-from-bottom\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"nectar-fancy-box using-img  has-animation min_height_tablet_550px\" style=\"min-height: 70vh\" data-style=\"hover_desc\" data-border-radius=\"default\" data-animation=\"fade-in-from-bottom\" data-bg-animation=\"long_zoom\" data-border=\"\" data-delay=\"0\" data-alignment=\"left\" data-color=\"accent-color\" ><div class=\"box-bg\"  data-nectar-img-src=\"https:\/\/stella.villas\/wp-content\/uploads\/2023\/04\/cycling.jpg\"><\/div><div class=\"inner\"><div class=\"heading-wrap\"><span class=\"im-icon-wrap\" data-color=\"accent-color\"><span><svg role=\"presentation\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"30\" height=\"30\" viewbox=\"0 0 33 32\">\n        <path d=\"M6 25c-3.308 0-6-2.693-6-6s2.692-6 6-6 6 2.693 6 6c0 3.307-2.692 6-6 6zM6 14.333c-2.573 0-4.667 2.093-4.667 4.667s2.093 4.667 4.667 4.667 4.667-2.093 4.667-4.667c0-2.573-2.093-4.667-4.667-4.667zM27.333 25c-3.307 0-6-2.693-6-6s2.693-6 6-6 6 2.693 6 6c0 3.307-2.693 6-6 6zM27.333 14.333c-2.573 0-4.667 2.093-4.667 4.667s2.093 4.667 4.667 4.667 4.667-2.093 4.667-4.667c0-2.573-2.093-4.667-4.667-4.667zM15.333 20.333h-9.333c-0.269 0-0.513-0.163-0.616-0.412-0.104-0.251-0.047-0.536 0.144-0.727l7.408-7.412c0.26-0.259 0.683-0.259 0.943 0s0.26 0.684 0 0.943l-6.269 6.269h7.455l8.801-8.497c0.263-0.252 0.689-0.251 0.943 0.019 0.253 0.265 0.249 0.688-0.019 0.943l-8.993 8.685c-0.124 0.121-0.291 0.189-0.463 0.189zM27.333 19.667c-0.269 0-0.524-0.164-0.624-0.432l-4-10.667c-0.129-0.344 0.045-0.729 0.389-0.86 0.345-0.135 0.729 0.047 0.859 0.391l4 10.667c0.129 0.347-0.045 0.729-0.389 0.859-0.077 0.029-0.156 0.043-0.235 0.043zM15.333 19.667c-0.289 0-0.556-0.191-0.64-0.481l-2.667-9.333c-0.101-0.356 0.104-0.724 0.459-0.825 0.352-0.107 0.723 0.104 0.824 0.46l2.667 9.333c0.101 0.356-0.104 0.724-0.459 0.823-0.063 0.016-0.124 0.024-0.184 0.024zM14 9.667h-4c-0.368 0-0.667-0.3-0.667-0.667s0.299-0.667 0.667-0.667h4c0.368 0 0.667 0.3 0.667 0.667s-0.299 0.667-0.667 0.667zM23.333 8.333h-1.333c-0.367 0-0.667-0.3-0.667-0.667s0.3-0.667 0.667-0.667h1.333c0.367 0 0.667 0.3 0.667 0.667s-0.3 0.667-0.667 0.667zM14.685 17.4c-0.187 0-0.371-0.080-0.503-0.229-0.241-0.279-0.212-0.699 0.065-0.94l8.897-7.733c0.276-0.245 0.695-0.212 0.94 0.065 0.243 0.279 0.213 0.697-0.065 0.94l-8.899 7.733c-0.124 0.111-0.28 0.164-0.436 0.164z\"><\/path>\n        <\/svg><\/span><\/span>\n<h4>Radtouren<\/h4>\n<\/div><div class=\"hover-content\">Erkunden Sie die malerische Landschaft auf unseren organisierten Radtouren. Unsere erfahrenen Reiseleiter nehmen Sie mit auf eine Reise durch malerische D\u00f6rfer, \u00fcppige Olivenhaine und atemberaubende Berglandschaften. Mit Strecken, die f\u00fcr Radfahrer aller Schwierigkeitsgrade geeignet sind, von gem\u00fctlichen Fahrten bis hin zu anspruchsvollen Bergtouren, ist f\u00fcr jeden etwas dabei. Unsere hochmodernen Fahrr\u00e4der und Ausr\u00fcstungen sorgen f\u00fcr eine komfortable und sichere Fahrt, w\u00e4hrend unsere sachkundigen F\u00fchrer interessante Einblicke in die Geschichte und Kultur der Region geben. Steigen Sie also auf Ihr Fahrrad und erleben Sie mit uns ein unvergessliches Radabenteuer.<\/div><\/div>   <\/div>\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-6 wpb_column column_container vc_column_container col child_column has-animation no-extra-padding inherit_tablet inherit_phone\"   data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"fade-in-from-bottom\" data-delay=\"50\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"nectar-fancy-box using-img  has-animation min_height_tablet_550px\" style=\"min-height: 70vh\" data-style=\"hover_desc\" data-border-radius=\"default\" data-animation=\"fade-in-from-bottom\" data-bg-animation=\"long_zoom\" data-border=\"\" data-delay=\"0\" data-alignment=\"left\" data-color=\"accent-color\" ><div class=\"box-bg\"  data-nectar-img-src=\"https:\/\/stella.villas\/wp-content\/uploads\/2017\/07\/kourtaliotiko3.jpg\"><\/div><div class=\"inner\"><div class=\"heading-wrap\"><span class=\"im-icon-wrap\" data-color=\"accent-color\"><span><svg role=\"presentation\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"30\" height=\"30\" viewbox=\"0 0 32 32\">\n        <path d=\"M1.391 31.732c-0.107 0-0.213-0.027-0.313-0.079-0.324-0.175-0.447-0.579-0.273-0.904l6.5-12.167c0.108-0.2 0.313-0.336 0.541-0.352 0.241-0.024 0.451 0.085 0.584 0.273l3.321 4.568 4.947-11.112c0.104-0.235 0.333-0.388 0.591-0.396 0.279-0.024 0.495 0.135 0.612 0.361l4.885 9.549 1.917-4.028c0.113-0.243 0.356-0.409 0.617-0.38 0.263 0.005 0.497 0.167 0.599 0.409l5.417 12.919c0.141 0.341-0.019 0.732-0.359 0.869-0.339 0.143-0.731-0.019-0.871-0.357l-4.841-11.544-1.86 3.907c-0.109 0.229-0.339 0.377-0.592 0.38-0.259-0.021-0.488-0.139-0.603-0.36l-4.864-9.508-4.849 10.891c-0.096 0.219-0.303 0.364-0.539 0.393-0.244 0.027-0.469-0.084-0.609-0.271l-3.375-4.64-5.999 11.229c-0.115 0.22-0.345 0.348-0.585 0.348zM13.252 26.315c-0.111 0-0.221-0.028-0.324-0.084l-2.3-1.281-2.516 1.292c-0.192 0.099-0.423 0.096-0.616-0.003l-2.747-1.453c-0.325-0.175-0.449-0.579-0.277-0.901 0.173-0.328 0.576-0.451 0.901-0.279l2.439 1.292 2.525-1.297c0.199-0.099 0.433-0.093 0.628 0.013l2.088 1.16 2.46-3.508c0.059-0.084 0.139-0.153 0.229-0.203l2.584-1.388c0.257-0.139 0.576-0.088 0.784 0.115l2.724 2.695c0.052 0.049 0.095 0.112 0.129 0.177l1.035 2.091 1.956-0.976c0.073-0.033 0.151-0.060 0.232-0.068l2.723-0.276c0.353-0.060 0.693 0.224 0.731 0.591 0.036 0.364-0.229 0.693-0.596 0.732l-2.599 0.265-2.448 1.224c-0.156 0.084-0.341 0.093-0.511 0.033-0.168-0.057-0.307-0.177-0.385-0.336l-1.284-2.591-2.293-2.271-2.009 1.084-2.715 3.867c-0.131 0.183-0.336 0.284-0.548 0.284zM4.723 16.395c-0.171 0-0.341-0.065-0.472-0.195l-2.828-2.827c-0.26-0.259-0.26-0.684 0-0.943s0.683-0.259 0.943 0l2.828 2.828c0.26 0.259 0.26 0.684 0 0.943-0.131 0.129-0.301 0.193-0.471 0.193zM1.893 16.395c-0.171 0-0.341-0.065-0.472-0.195-0.26-0.259-0.26-0.684 0-0.943l2.828-2.828c0.26-0.259 0.683-0.259 0.943 0s0.26 0.684 0 0.943l-2.828 2.828c-0.129 0.131-0.3 0.195-0.471 0.195zM11.389 15.061c-0.171 0-0.341-0.065-0.472-0.195l-2.828-2.827c-0.26-0.259-0.26-0.684 0-0.943s0.683-0.259 0.943 0l2.828 2.828c0.26 0.259 0.26 0.684 0 0.943-0.131 0.129-0.301 0.193-0.471 0.193zM8.56 15.061c-0.171 0-0.341-0.065-0.472-0.195-0.26-0.259-0.26-0.684 0-0.943l2.828-2.828c0.26-0.259 0.683-0.259 0.943 0s0.26 0.684 0 0.943l-2.828 2.828c-0.129 0.131-0.3 0.195-0.471 0.195zM10.624 9.648h-5.156c-2.905 0-4.857-1.703-4.857-4.243 0-2.781 2.224-5.137 4.857-5.137 1.744 0 2.996 0.471 3.807 1.42 0.436-0.168 0.889-0.248 1.349-0.248 2.191 0 3.889 2.473 3.889 4.608 0 2.087-1.636 3.6-3.889 3.6zM5.468 1.607c-1.877 0-3.524 1.776-3.524 3.805 0 2.143 1.897 2.912 3.524 2.912h5.157c1.505 0 2.556-0.932 2.556-2.263 0-1.444-1.204-3.275-2.556-3.275-0.424 0-0.841 0.115-1.24 0.34l-0.567 0.316-0.333-0.555c-0.523-0.879-1.483-1.281-3.017-1.281z\"><\/path>\n        <\/svg><\/span><\/span>\n<h4>Fluss-Trekking in der Kourtaliotis-Schlucht<\/h4>\n<\/div><div class=\"hover-content\">Erleben Sie die nat\u00fcrliche Sch\u00f6nheit der Kourtaliotis-Schlucht auf unseren spannenden Fluss-Trekking-Touren. Unsere erfahrenen Reiseleiter begleiten Sie auf einer Reise durch das gewundene Flussbett und bieten Ihnen die M\u00f6glichkeit, in kristallklaren Pools zu schwimmen. Bestaunen Sie die atemberaubenden Felsformationen und die \u00fcppige Vegetation, die die Canyonw\u00e4nde s\u00e4umen, w\u00e4hrend Sie Ihren Weg tiefer in das Herz der Schlucht einschlagen. Mit Routen, die f\u00fcr alle Erfahrungsstufen geeignet sind, bieten unsere Fluss-Trekking-Touren garantiert ein unvergessliches Abenteuer.<\/div><\/div>   <\/div>\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n<\/div><\/div><div id=\"fws_6a97bae619cd9\" data-midnight=\"\" data-column-margin=\"20px\" class=\"wpb_row vc_row-fluid vc_row inner_row\"  style=\"\"><div class=\"row-bg-wrap\"> <div class=\"row-bg\" ><\/div> <\/div><div class=\"row_col_wrap_12_inner col span_12  left\">\n\t<div  class=\"vc_col-sm-6 wpb_column column_container vc_column_container col child_column has-animation no-extra-padding inherit_tablet inherit_phone\"   data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"fade-in-from-bottom\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"nectar-fancy-box using-img  has-animation min_height_tablet_550px\" style=\"min-height: 70vh\" data-style=\"hover_desc\" data-border-radius=\"default\" data-animation=\"fade-in-from-bottom\" data-bg-animation=\"long_zoom\" data-border=\"\" data-delay=\"0\" data-alignment=\"left\" data-color=\"accent-color\" ><div class=\"box-bg\"  data-nectar-img-src=\"https:\/\/stella.villas\/wp-content\/uploads\/2017\/07\/aptera5.jpg\"><\/div><div class=\"inner\"><div class=\"heading-wrap\"><span class=\"im-icon-wrap\" data-color=\"accent-color\"><span><svg role=\"presentation\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"30\" height=\"30\" viewbox=\"0 0 32 32\">\n        <path d=\"M22.167 24.667h-20c-0.367 0-0.667-0.3-0.667-0.667v-12c0-0.367 0.3-0.667 0.667-0.667h20c0.367 0 0.667 0.3 0.667 0.667v12c0 0.367-0.3 0.667-0.667 0.667zM2.833 23.333h18.667v-10.667h-18.667v10.667zM30.167 27.333c-0.071 0-0.14-0.012-0.211-0.033l-8-2.667c-0.271-0.088-0.456-0.347-0.456-0.633v-12c0-0.287 0.185-0.541 0.456-0.633l8-2.667c0.204-0.068 0.425-0.031 0.6 0.089 0.175 0.127 0.277 0.325 0.277 0.537v17.333c0 0.216-0.103 0.417-0.277 0.54-0.115 0.091-0.251 0.133-0.389 0.133zM22.833 23.521l6.667 2.221v-15.483l-6.667 2.223v11.039zM7.167 12c-3.307 0-6-2.693-6-6s2.693-6 6-6 6 2.693 6 6-2.693 6-6 6zM7.167 1.333c-2.573 0-4.667 2.093-4.667 4.667s2.093 4.667 4.667 4.667 4.667-2.093 4.667-4.667-2.093-4.667-4.667-4.667zM17.833 12c-3.307 0-6-2.693-6-6s2.693-6 6-6 6 2.693 6 6-2.693 6-6 6zM17.833 1.333c-2.573 0-4.667 2.093-4.667 4.667s2.093 4.667 4.667 4.667 4.667-2.093 4.667-4.667-2.093-4.667-4.667-4.667zM2.751 32c-0.195 0-0.393-0.088-0.527-0.255-0.227-0.293-0.175-0.711 0.116-0.937l9.417-7.333c0.291-0.227 0.708-0.175 0.935 0.117s0.175 0.708-0.115 0.935l-9.417 7.333c-0.124 0.095-0.267 0.14-0.409 0.14zM22.917 32c-0.14 0-0.287-0.045-0.411-0.14l-9.417-7.333c-0.289-0.227-0.341-0.641-0.115-0.935 0.227-0.292 0.641-0.344 0.935-0.117l9.417 7.333c0.291 0.227 0.343 0.644 0.116 0.937-0.133 0.167-0.328 0.255-0.525 0.255zM12.833 32c-0.367 0-0.667-0.3-0.667-0.667v-6.667c0-0.367 0.3-0.667 0.667-0.667s0.667 0.3 0.667 0.667v6.667c0 0.367-0.3 0.667-0.667 0.667z\"><\/path>\n        <\/svg><\/span><\/span>\n<h4>Besichtigung und kulturelle Touren<\/h4>\n<\/div><div class=\"hover-content\">Entdecken Sie die reiche Geschichte und Kultur der Region auf unseren Besichtigungs- und Kulturtouren. Besuchen Sie faszinierende arch\u00e4ologische St\u00e4tten, bezaubernde D\u00f6rfer und historische Sehensw\u00fcrdigkeiten, w\u00e4hrend unsere sachkundigen Reiseleiter Ihnen faszinierende Einblicke in die lokalen Br\u00e4uche und Traditionen geben. Mit Touren, die auf Ihre Interessen und Vorlieben zugeschnitten sind, ist f\u00fcr jeden etwas dabei. Ganz gleich, ob Sie ein Geschichtsliebhaber, ein Feinschmecker sind oder einfach nur in die lokale Kultur eintauchen m\u00f6chten, unsere Besichtigungs- und Kulturtouren bieten ein einzigartiges und unvergessliches Erlebnis.<\/div><\/div>   <\/div>\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-6 wpb_column column_container vc_column_container col child_column has-animation no-extra-padding inherit_tablet inherit_phone\"   data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"fade-in-from-bottom\" data-delay=\"50\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"nectar-fancy-box using-img  min_height_tablet_550px\" style=\"min-height: 70vh\" data-style=\"hover_desc\" data-border-radius=\"default\" data-animation=\"\" data-bg-animation=\"long_zoom\" data-border=\"\" data-delay=\"\" data-alignment=\"left\" data-color=\"accent-color\" ><div class=\"box-bg\"  data-nectar-img-src=\"https:\/\/stella.villas\/wp-content\/uploads\/2023\/04\/plakias-cliff.jpg\"><\/div><div class=\"inner\"><div class=\"heading-wrap\"><span class=\"im-icon-wrap\" data-color=\"accent-color\"><span><svg role=\"presentation\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"30\" height=\"30\" viewbox=\"0 0 32 32\">\n        <path d=\"M16 28.893c-2.205 0-4-1.795-4-4s1.795-4 4-4c2.205 0 4 1.795 4 4s-1.795 4-4 4zM16 22.227c-1.471 0-2.667 1.195-2.667 2.667s1.196 2.667 2.667 2.667c1.472 0 2.667-1.195 2.667-2.667s-1.195-2.667-2.667-2.667zM16 21.505c-0.368 0-0.667-0.3-0.667-0.667v-16c0-0.367 0.299-0.667 0.667-0.667s0.667 0.3 0.667 0.667v16c0 0.367-0.299 0.667-0.667 0.667zM16 31.56c-3.676 0-6.667-2.989-6.667-6.667 0-2.385 1.267-4.552 3.333-5.748v-15.372c0-1.839 1.496-3.333 3.333-3.333s3.333 1.495 3.333 3.333v15.373c2.067 1.195 3.333 3.361 3.333 5.748 0 3.676-2.991 6.665-6.667 6.665zM16 1.773c-1.103 0-2 0.897-2 2v15.773c0 0.251-0.143 0.481-0.368 0.593-1.829 0.917-2.965 2.735-2.965 4.751 0 2.943 2.392 5.333 5.333 5.333s5.333-2.391 5.333-5.333c0-2.019-1.136-3.836-2.967-4.751-0.224-0.112-0.367-0.344-0.367-0.593v-15.773c0-1.104-0.897-2-2-2zM20.667 7.505h-1.333c-0.367 0-0.667-0.3-0.667-0.667s0.3-0.667 0.667-0.667h1.333c0.367 0 0.667 0.3 0.667 0.667s-0.3 0.667-0.667 0.667zM20.667 10.172h-1.333c-0.367 0-0.667-0.3-0.667-0.667s0.3-0.667 0.667-0.667h1.333c0.367 0 0.667 0.3 0.667 0.667s-0.3 0.667-0.667 0.667zM20.667 12.839h-1.333c-0.367 0-0.667-0.3-0.667-0.667s0.3-0.667 0.667-0.667h1.333c0.367 0 0.667 0.3 0.667 0.667s-0.3 0.667-0.667 0.667z\"><\/path>\n        <\/svg><\/span><\/span>\n<h4>Klettern in Plakias-Klippe<\/h4>\n<\/div><div class=\"hover-content\">ordern Sie sich selbst mit unseren spannenden Klettertouren in Plakias-Klippe heraus. Unsere erfahrenen F\u00fchrer stellen Ihnen die n\u00f6tige Ausr\u00fcstung und Anleitung zur Verf\u00fcgung, w\u00e4hrend Sie die zerkl\u00fcftete Klippe hinaufsteigen und die atemberaubende Aussicht auf die umliegende K\u00fcste genie\u00dfen. Mit Strecken f\u00fcr alle Niveaus von Kletterern, vom Anf\u00e4nger bis zum Experten, haben Sie die M\u00f6glichkeit, Ihre F\u00e4higkeiten zu testen und Ihre Grenzen zu \u00fcberschreiten.<\/div><\/div>   <\/div>\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n<\/div><\/div><div id=\"fws_6a97bae61bba1\" data-midnight=\"\" data-column-margin=\"20px\" class=\"wpb_row vc_row-fluid vc_row inner_row\"  style=\"\"><div class=\"row-bg-wrap\"> <div class=\"row-bg\" ><\/div> <\/div><div class=\"row_col_wrap_12_inner col span_12  left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col child_column has-animation no-extra-padding inherit_tablet inherit_phone\"   data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"fade-in-from-bottom\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"nectar-fancy-box using-img  has-animation min_height_tablet_550px\" style=\"min-height: 70vh\" data-style=\"hover_desc\" data-border-radius=\"default\" data-animation=\"fade-in-from-bottom\" data-bg-animation=\"long_zoom\" data-border=\"\" data-delay=\"0\" data-alignment=\"left\" data-color=\"accent-color\" ><div class=\"box-bg\"  data-nectar-img-src=\"https:\/\/stella.villas\/wp-content\/uploads\/2023\/07\/authentic-local-food.jpg\"><\/div><div class=\"inner\"><div class=\"heading-wrap\"><span class=\"im-icon-wrap\" data-color=\"accent-color\"><span><svg role=\"presentation\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"30\" height=\"30\" viewbox=\"0 0 41 32\">\n        <path d=\"M10.209 17.709c-3.295 0-5.968-5.087-5.968-8.412 0-3.291 2.677-5.969 5.968-5.969 3.289 0 5.967 2.677 5.967 5.969 0 3.321-2.672 8.412-5.967 8.412zM10.209 4.665c-2.556 0-4.635 2.080-4.635 4.635 0 2.667 2.167 7.080 4.635 7.080s4.633-4.413 4.633-7.080c0-2.556-2.079-4.635-4.633-4.635zM30.211 17.709c-3.295 0-5.972-5.087-5.972-8.412 0-3.291 2.68-5.969 5.972-5.969 3.289 0 5.967 2.677 5.967 5.969 0 3.321-2.675 8.412-5.967 8.412zM30.211 4.665c-2.555 0-4.639 2.080-4.639 4.635 0 2.667 2.167 7.080 4.639 7.080 2.467 0 4.633-4.413 4.633-7.080 0-2.556-2.079-4.635-4.633-4.635zM10.209 28.671c-5.629 0-10.209-3.196-10.209-7.135 0-2.661 2.095-6.223 5.336-9.072 0.277-0.243 0.699-0.215 0.941 0.061 0.244 0.276 0.216 0.697-0.060 0.943-2.92 2.565-4.883 5.807-4.883 8.068 0 3.195 3.981 5.8 8.876 5.8 1.061 0 1.732-0.139 2.635-0.352 0.356-0.083 0.717 0.139 0.801 0.497s-0.139 0.716-0.497 0.804c-0.964 0.227-1.737 0.385-2.94 0.385zM18.244 17.639c-0.228 0-0.451-0.117-0.575-0.328-0.821-1.391-1.959-2.472-3.476-3.844-0.273-0.249-0.295-0.671-0.047-0.944 0.248-0.272 0.669-0.295 0.941-0.048 1.605 1.455 2.813 2.603 3.729 4.156 0.187 0.315 0.083 0.725-0.235 0.915-0.107 0.063-0.223 0.093-0.339 0.093zM21.839 17.639c-0.115 0-0.232-0.028-0.339-0.091-0.317-0.191-0.419-0.595-0.235-0.915 0.752-1.275 1.893-2.26 3.099-3.307 0.32-0.276 0.645-0.557 0.964-0.848 0.272-0.247 0.695-0.227 0.943 0.045 0.248 0.273 0.227 0.695-0.047 0.941-0.325 0.299-0.659 0.584-0.987 0.868-1.12 0.972-2.18 1.888-2.82 2.972-0.128 0.216-0.349 0.333-0.579 0.333zM30.211 28.665c-1.099 0-2.2-0.132-3.273-0.377-0.357-0.084-0.581-0.443-0.497-0.805 0.085-0.36 0.432-0.584 0.803-0.496 0.972 0.228 1.972 0.344 2.971 0.344 4.893 0 8.872-2.597 8.872-5.791 0-2.261-1.965-5.505-4.883-8.068-0.276-0.247-0.305-0.665-0.060-0.943 0.243-0.276 0.664-0.305 0.939-0.060 3.244 2.845 5.337 6.408 5.337 9.071 0 3.932-4.58 7.125-10.208 7.125zM14.921 26.332c-2.205 0-4-1.776-4-3.963 0-2.219 1.701-3.961 3.875-3.961 0.909 0 1.515 0.32 2.032 0.667 0.305 0.205 0.389 0.62 0.184 0.925-0.204 0.305-0.62 0.387-0.924 0.187-0.429-0.288-0.761-0.443-1.291-0.443-1.425 0-2.541 1.152-2.541 2.628 0 1.448 1.196 2.628 2.667 2.628 0.583 0 1.18-0.203 1.639-0.557 0.292-0.224 0.711-0.169 0.935 0.12 0.224 0.295 0.171 0.711-0.121 0.935-0.697 0.539-1.568 0.835-2.453 0.835zM26.968 26.332c-0.885 0-1.756-0.299-2.453-0.836-0.293-0.224-0.347-0.641-0.123-0.935 0.224-0.289 0.641-0.347 0.933-0.12 0.46 0.356 1.057 0.557 1.639 0.557 1.471 0 2.667-1.177 2.667-2.629 0-1.472-1.12-2.628-2.54-2.628-0.529 0-0.861 0.156-1.293 0.443-0.305 0.2-0.721 0.123-0.924-0.184s-0.123-0.72 0.185-0.925c0.519-0.347 1.123-0.667 2.029-0.667 2.175 0 3.873 1.743 3.873 3.961 0.007 2.187-1.789 3.963-3.993 3.963zM25.117 22.972h-8c-0.368 0-0.667-0.301-0.667-0.667 0-0.367 0.299-0.667 0.667-0.667h8c0.367 0 0.667 0.3 0.667 0.667 0 0.365-0.3 0.667-0.667 0.667z\"><\/path>\n        <\/svg><\/span><\/span>\n<h4>Authentisches lokales Essen<\/h4>\n<\/div><div class=\"hover-content\">Erleben Sie die k\u00f6stlichen Aromen der Region mit unseren authentischen lokalen Gastronomie-Touren. Probieren Sie traditionelle Gerichte aus regionalen Zutaten und erfahren Sie mehr \u00fcber die einzigartigen kulinarischen Traditionen, die \u00fcber Generationen weitergegeben wurden. Unsere sachkundigen Reiseleiter f\u00fchren Sie zu versteckten diamantartigen Restaurants und M\u00e4rkten, wo Sie die reichen Aromen und D\u00fcfte der lokalen K\u00fcche genie\u00dfen k\u00f6nnen. Von frischen Meeresfr\u00fcchten bis hin zu saftigem Fleisch bieten unsere kulinarischen Touren einen wahrhaft authentischen Geschmack der Region.<\/div><\/div>   <\/div>\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>","protected":false},"excerpt":{"rendered":"Live it to the FullestEXPERIENCES There's no shortage of activities to enjoy during your stay in the area....","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-1703","page","type-page","status-publish"],"acf":[],"_links":{"self":[{"href":"https:\/\/stella.villas\/de\/wp-json\/wp\/v2\/pages\/1703","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stella.villas\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/stella.villas\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/stella.villas\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/stella.villas\/de\/wp-json\/wp\/v2\/comments?post=1703"}],"version-history":[{"count":14,"href":"https:\/\/stella.villas\/de\/wp-json\/wp\/v2\/pages\/1703\/revisions"}],"predecessor-version":[{"id":3582,"href":"https:\/\/stella.villas\/de\/wp-json\/wp\/v2\/pages\/1703\/revisions\/3582"}],"wp:attachment":[{"href":"https:\/\/stella.villas\/de\/wp-json\/wp\/v2\/media?parent=1703"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}